{"id":56,"count":28,"description":"","link":"https:\/\/arsalgida.com\/de\/kategori\/zeytin-ve-zeytin-yaglari\/","name":"Zeytin ve Zeytin Ya\u011flar\u0131","slug":"zeytin-ve-zeytin-yaglari","taxonomy":"product_cat","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Zeytin ve Zeytin Ya\u011flar\u0131 Archives - Arsal G\u0131da<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arsalgida.com\/de\/kategori\/zeytin-ve-zeytin-yaglari\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zeytin ve Zeytin Ya\u011flar\u0131 Archives - Arsal G\u0131da\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arsalgida.com\/de\/kategori\/zeytin-ve-zeytin-yaglari\/\" \/>\n<meta property=\"og:site_name\" content=\"Arsal G\u0131da\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/arsalgida.com\/kategori\/zeytin-ve-zeytin-yaglari\/\",\"url\":\"https:\/\/arsalgida.com\/kategori\/zeytin-ve-zeytin-yaglari\/\",\"name\":\"Zeytin ve Zeytin Ya\u011flar\u0131 Archives - Arsal G\u0131da\",\"isPartOf\":{\"@id\":\"https:\/\/arsalgida.com\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/arsalgida.com\/kategori\/zeytin-ve-zeytin-yaglari\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/arsalgida.com\/kategori\/zeytin-ve-zeytin-yaglari\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/arsalgida.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zeytin ve Zeytin Ya\u011flar\u0131\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/arsalgida.com\/#website\",\"url\":\"https:\/\/arsalgida.com\/\",\"name\":\"Arsal G\u0131da\",\"description\":\"1979 &#039;dan G\u00fcn\u00fcm\u00fcze\",\"publisher\":{\"@id\":\"https:\/\/arsalgida.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/arsalgida.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/arsalgida.com\/#organization\",\"name\":\"Arsal G\u0131da\",\"url\":\"https:\/\/arsalgida.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/arsalgida.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/arsalgida.com\/wp-content\/uploads\/2020\/03\/5555.png\",\"contentUrl\":\"https:\/\/arsalgida.com\/wp-content\/uploads\/2020\/03\/5555.png\",\"width\":150,\"height\":93,\"caption\":\"Arsal G\u0131da\"},\"image\":{\"@id\":\"https:\/\/arsalgida.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zeytin ve Zeytin Ya\u011flar\u0131 Archives - Arsal G\u0131da","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arsalgida.com\/de\/kategori\/zeytin-ve-zeytin-yaglari\/","og_locale":"de_DE","og_type":"article","og_title":"Zeytin ve Zeytin Ya\u011flar\u0131 Archives - Arsal G\u0131da","og_url":"https:\/\/arsalgida.com\/de\/kategori\/zeytin-ve-zeytin-yaglari\/","og_site_name":"Arsal G\u0131da","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/arsalgida.com\/kategori\/zeytin-ve-zeytin-yaglari\/","url":"https:\/\/arsalgida.com\/kategori\/zeytin-ve-zeytin-yaglari\/","name":"Zeytin ve Zeytin Ya\u011flar\u0131 Archives - Arsal G\u0131da","isPartOf":{"@id":"https:\/\/arsalgida.com\/#website"},"breadcrumb":{"@id":"https:\/\/arsalgida.com\/kategori\/zeytin-ve-zeytin-yaglari\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/arsalgida.com\/kategori\/zeytin-ve-zeytin-yaglari\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/arsalgida.com\/"},{"@type":"ListItem","position":2,"name":"Zeytin ve Zeytin Ya\u011flar\u0131"}]},{"@type":"WebSite","@id":"https:\/\/arsalgida.com\/#website","url":"https:\/\/arsalgida.com\/","name":"Arsal G\u0131da","description":"1979 &#039;dan G\u00fcn\u00fcm\u00fcze","publisher":{"@id":"https:\/\/arsalgida.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arsalgida.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/arsalgida.com\/#organization","name":"Arsal G\u0131da","url":"https:\/\/arsalgida.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/arsalgida.com\/#\/schema\/logo\/image\/","url":"https:\/\/arsalgida.com\/wp-content\/uploads\/2020\/03\/5555.png","contentUrl":"https:\/\/arsalgida.com\/wp-content\/uploads\/2020\/03\/5555.png","width":150,"height":93,"caption":"Arsal G\u0131da"},"image":{"@id":"https:\/\/arsalgida.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/arsalgida.com\/de\/wp-json\/wp\/v2\/product_cat\/56","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arsalgida.com\/de\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/arsalgida.com\/de\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/arsalgida.com\/de\/wp-json\/wp\/v2\/product?product_cat=56"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}